{"id":86105,"date":"2008-10-06T23:50:53","date_gmt":"2008-10-06T23:50:53","guid":{"rendered":"https:\/\/1875.ch\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/"},"modified":"2020-05-26T23:57:08","modified_gmt":"2020-05-26T23:57:08","slug":"ce-que-la-crise-va-changer-pour-le-monde-de-la-finance","status":"publish","type":"post","link":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/","title":{"rendered":"Ce que la crise va changer pour le monde de la finance"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;2&#8243; top_padding=&#8220;5&#8243; bottom_padding=&#8220;2&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_percent=&#8220;100&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column column_width_percent=&#8220;100&#8243; align_horizontal=&#8220;align_center&#8220; gutter_size=&#8220;3&#8243; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;0&#8243; mobile_width=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading auto_text=&#8220;yes&#8220; separator=&#8220;yes&#8220; separator_color=&#8220;yes&#8220;][\/vc_custom_heading][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/1&#8243;][vc_column_text]<\/p>\n<div id=\"pg-4781-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-4781-1\">\n<div id=\"pgc-4781-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-4781-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2793-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2793-1\">\n<div id=\"pgc-2793-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2793-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2962-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2962-1\">\n<div id=\"pgc-2962-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2962-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>Comment l&#8217;industrie financi\u00e8re, qui a d\u00e9j\u00e0 d\u00e9truit 120000 emplois, sortira-t-elle de la crise? Dans quel environnement travailleront les banquiers ces prochaines ann\u00e9es? Telles sont les questions qui taraudent en ce moment les dirigeants de banque, qui, apr\u00e8s avoir par\u00e9 aux urgences de la crise, r\u00e9fl\u00e9chissent aux strat\u00e9gies de demain. Synth\u00e8se des r\u00e9flexions glan\u00e9es aupr\u00e8s de leaders de la finance<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_percent=&#8220;100&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; shape_dividers=&#8220;&#8220;][vc_column width=&#8220;1\/1&#8243;][vc_single_image media=&#8220;83406&#8243; media_width_percent=&#8220;100&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;2&#8243; top_padding=&#8220;2&#8243; bottom_padding=&#8220;5&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_percent=&#8220;100&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; shape_dividers=&#8220;&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<div id=\"pg-4781-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-4781-1\">\n<div id=\"pgc-4781-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-4781-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2793-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2793-1\">\n<div id=\"pgc-2793-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2793-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2962-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2962-1\">\n<div id=\"pgc-2962-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2962-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>Gestion de fortune: le retour<\/p>\n<p>Apr\u00e8s cinq ans durant lesquels les m\u00e9tiers ultradynamiques de banque d&#8217;affaires ont accapar\u00e9 l&#8217;attention strat\u00e9gique de toutes les banques qui pouvaient s&#8217;y lancer, c&#8217;est \u00e0 pr\u00e9sent la gestion de fortune qui redevient le m\u00e9tier phare. Une \u00e9volution positive pour la Suisse. D\u00e9sormais, Brady Dougan, CEO de Credit Suisse, fait du private banking sa<br \/>\npriorit\u00e9, m\u00eame aux Etats-Unis. UBS op\u00e8re un recentrage drastique sur ce m\u00e9tier. Et les banquiers priv\u00e9s suisses, comme Patrick Odier, observent d&#8217;importants afflux de client\u00e8le en qu\u00eate de refuge. Partout, des banquiers d&#8217;affaires se recyclent, par<br \/>\ncentaines, dans des unit\u00e9s de gestion. D\u00e9sormais, les comp\u00e9tences de banque d&#8217;affaires se mettent au service des unit\u00e9s de gestion priv\u00e9e, surtout en Asie.<\/p>\n<p>Les fortunes \u00e9mergentes<\/p>\n<p>Sa fortune est d\u00e9clar\u00e9e, entrepreneuriale, il est jeune,<br \/>\net avide de risque. Ce client de demain se trouve principalement en Asie. Les banques de gestion du monde s&#8217;organisent pour s&#8217;adapter \u00e0 son profil et \u00e0 ses pr\u00e9f\u00e9rences pour certains produits, comme les structur\u00e9s sur actions, le n\u00e9goce d&#8217;actions agressif, les<br \/>\ndevises, l&#8217;immobilier priv\u00e9 et commercial. D\u00e9sormais, les logiciels de produits financiers des banques, leurs back offices, et leurs capacit\u00e9s de structuration passent<br \/>\nau \u00absi\u00e8cle asiatique\u00bb. Car en 2012, \u00abl&#8217;Asie d\u00e9passera l&#8217;Europe comme march\u00e9 de la gestion de fortune, avec des grandes fortunes pesant 13,9 milliards de dollars,<br \/>\ncontre 13,5 milliards pour l&#8217;Europe\u00bb, selon Philippe Theytaz, directeur de la strat\u00e9gie chez SG Private Banking Singapour, de passage au Finance Summit qui s&#8217;est d\u00e9roul\u00e9 jeudi \u00e0 Gen\u00e8ve. 80% des fortunes en Asie \u00e9manent d&#8217;entrepreneurs de premi\u00e8re g\u00e9n\u00e9ration, contre 25% en Europe! Avec la crise, ces investisseurs ont gagn\u00e9 en maturit\u00e9, et sont plus r\u00e9ceptifs \u00e0 la philosophie de gestion suisse: diversification, allocation d&#8217;actifs, \u00abc&#8217;est un langage qu&#8217;ils comprennent mieux\u00bb, note le strat\u00e8ge.<\/p>\n<p>Protection des donn\u00e9es<\/p>\n<p>Les affaires r\u00e9centes d&#8217;UBS et du fisc am\u00e9ricain, de la banque liechtensteinoise LGT et du fisc allemand, ou de Julius B\u00e4r et du site internet am\u00e9ricain, ont r\u00e9v\u00e9l\u00e9 combien les banques sont vuln\u00e9rables \u00e0 la divulgation d&#8217;informations sensibles. Ces \u00e9v\u00e9nements font r\u00e9fl\u00e9chir: comment pr\u00e9server la s\u00e9curit\u00e9 de l&#8217;information du client&#8230; et la r\u00e9putation de l&#8217;\u00e9tablissement? Les banques r\u00e9fl\u00e9chissent \u00e0 une surveillance accrue des points<br \/>\nd&#8217;acc\u00e8s \u00e0 l&#8217;information strat\u00e9gique. \u00abIl faut s&#8217;assurer que n&#8217;importe qui ne peut pas y acc\u00e9der, d\u00e9velopper des outils de tra\u00e7abilit\u00e9 permettant de retrouver l&#8217;historique<br \/>\nde ce qui a \u00e9t\u00e9 transf\u00e9r\u00e9 depuis un ordinateur, et pr\u00e9voir un syst\u00e8me d&#8217;alertes\u00bb, souligne St\u00e9phane Koch, sp\u00e9cialiste de la gestion strat\u00e9gique de l&#8217;information et<br \/>\nfondateur d&#8217;Intelligenzia.net.<\/p>\n<p>La fin du \u00abnon d\u00e9clar\u00e9\u00bb<\/p>\n<p>L&#8217;affaire UBS-Bradley Birkenfeld aux Etats-Unis l&#8217;a annonc\u00e9: la gestion offshore non d\u00e9clar\u00e9e, c&#8217;est du pass\u00e9. Pour survivre, l&#8217;offshore devra emprunter des sch\u00e9mas et des structures l\u00e9gitimes. Exemple \u00abl&#8217;expertise en d\u00e9localisations fiscales de r\u00e9sidents d&#8217;Europe\u00bb, sugg\u00e8re Olivier Bizon, directeur ex\u00e9cutif de 1875 Finance. Dans cette expertise fiscale, souvent multi-juridictionnelle, les banques suisses implant\u00e9es en Europe excellent.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<\/p>\n<div id=\"pg-4781-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-4781-1\">\n<div id=\"pgc-4781-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-4781-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2793-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2793-1\">\n<div id=\"pgc-2793-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2793-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<div id=\"pg-2962-1\" class=\"panel-grid panel-has-style\">\n<div class=\"container panel-row-style panel-row-style-for-2962-1\">\n<div id=\"pgc-2962-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-2962-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>Acc\u00e8s (exc\u00e8s?) r\u00e9glementaire<\/p>\n<p>\u00abL&#8217;ann\u00e9e 2008 a g\u00e9n\u00e9r\u00e9, \u00e0 elle seule, un volume incroyable de r\u00e9glementations en Suisse!\u00bb a observ\u00e9 Didier de Montmollin, associ\u00e9 de l&#8217;\u00e9tude Secretan Troyanov, lors du Finance Summit. Sur le site internet de la Commission f\u00e9d\u00e9rale des banques, il constate une \u00abf\u00e9brilit\u00e9 impressionnante\u00bb: interdiction des ventes \u00e0 d\u00e9couvert, \u00e9toffement des r\u00e8gles contre les abus de march\u00e9 et les conflits d&#8217;int\u00e9r\u00eats, exigences de fonds propres revues \u00e0 la hausse&#8230; L&#8217;avocat met en garde contre la \u00abtentation d&#8217;imprimer des kilos de papier\u00bb, et contre la production automatique de r\u00e8glements<br \/>\nstandards, chez les banques, souvent peu pertinents, voire absurdes, quand la r\u00e9flexion et le sens critique sont absents du processus. Pour Antoine M\u00e9rieux,<br \/>\nd\u00e9l\u00e9gu\u00e9 g\u00e9n\u00e9ral de l&#8217;Association d&#8217;\u00e9conomie financi\u00e8re \u00e0 Paris, \u00abune nouvelle couche de r\u00e9glementation, si n\u00e9cessaire soit-elle, ne peut constituer la seule r\u00e9ponse; l&#8217;exp\u00e9rience de B\u00e2le II montre que chaque nouvelle r\u00e8gle suscite des tentatives de contournement allant \u00e0 l&#8217;encontre de l&#8217;objectif recherch\u00e9\u00bb. Aux EtatsUnis, on se dirige vers d&#8217;importantes r\u00e9formes. \u00abLa volont\u00e9 du Tr\u00e9sor de r\u00e9unir sous un seul toit la surveillance de tous les acteurs financiers, hedge funds, fonds de placement et soci\u00e9t\u00e9s financi\u00e8res est un plus\u00bb, estime Mark Mobius, de Templeton A.M.<\/p>\n<p>\u00abNormes \u00e9thiques strictes\u00bb<\/p>\n<p>La crise rend plus n\u00e9cessaires que jamais les travaux des intellectuels r\u00e9unis vendredi \u00e0 Gen\u00e8ve par l&#8217;Observatoire de la Finance. Le conflit d&#8217;int\u00e9r\u00eats, dans lequel se sont illustr\u00e9s les distributeurs de produits structur\u00e9s, \u00abfait partie de la nature humaine, mais on peut le contr\u00f4ler en rappelant aux acteurs qu&#8217;ils ont une responsabilit\u00e9 d\u00e9passant leur simple r\u00f4le \u00e9conomique, en leur demandant de suivre une charte \u00e9thique et<br \/>\nd\u00e9ontologique, \u00e0 la mani\u00e8re des m\u00e9decins\u00bb, sugg\u00e8re Paul Dembinsky, directeur de ce centre de recherche genevois travaillant pour \u00abune finance au service du bien commun\u00bb. Antoine M\u00e9rieux plaide pour \u00abdes normes \u00e9thiques strictes\u00bb, d\u00e9passant les simples \u00abcodes de bonne conduite &#8211; Bear Stearns en avait d&#8217;excellents\u00bb.<\/p>\n<p>La fin du culte du mod\u00e8le<\/p>\n<p>L&#8217;origine du capitalisme financier est aussi&#8230; universitaire! \u00abLa crise est \u00e0 chercher du c\u00f4t\u00e9 des Merton, Scholes et Prescott &#8211; autant de Nobel qui ont con\u00e7u les mod\u00e8les \u00e0 partir desquels les banques diversifient leurs risques\u00bb, rappellent Stefano Zamagni,<br \/>\nprofesseur \u00e0 l&#8217;Universit\u00e9 de Bologne. Cette science, n\u00e9e dans les ann\u00e9es 1950, a rapidement \u00ab\u00e9nonc\u00e9 un discours performatif, cr\u00e9ant sa propre r\u00e9alit\u00e9 avec les produits structur\u00e9s, brouillant la notion m\u00eame de risque\u00bb, pointe Paul Dembinski. Leur invention a \u00e9chapp\u00e9 aux p\u00e8res fondateurs de la th\u00e9orie financi\u00e8re. \u00abCeux-ci avaient tent\u00e9 de d\u00e9couper l&#8217;incertitude en deux parties: le \u00abrisque\u00bb, param\u00e9trable \u00e0 l&#8217;aide de probabilit\u00e9s; et \u00abl&#8217;incertitude\u00bb, que l&#8217;on ne peut diversifier\u00bb, d\u00e9crit l&#8217;universitaire genevois. Or, \u00abdans cet engouement, on a oubli\u00e9 de relativiser la partie contr\u00f4lable\u00bb. Une incertitude que la finance red\u00e9couvre aujourd&#8217;hui avec effroi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;2&#8243; top_padding=&#8220;5&#8243; bottom_padding=&#8220;2&#8243; back_color=&#8220;color-lxmt&#8220; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_percent=&#8220;100&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column column_width_percent=&#8220;100&#8243; align_horizontal=&#8220;align_center&#8220; gutter_size=&#8220;3&#8243; style=&#8220;light&#8220; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;0&#8243; mobile_width=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading text_weight=&#8220;300&#8243; text_height=&#8220;fontheight-357766&#8243; text_space=&#8220;fontspace-781688&#8243; separator=&#8220;yes&#8220; separator_color=&#8220;yes&#8220; sub_lead=&#8220;yes&#8220; css_animation=&#8220;curtain&#8220; animation_delay=&#8220;200&#8243; subheading=&#8220;Nous vous invitons \u00e0 prendre contact avec nous en cas de questions. Notre \u00e9quipe de sp\u00e9cialistes se tient \u00e0 votre disposition pour r\u00e9pondre \u00e0 vos questions et \u00e0 vos besoins.&#8220;]Pour en savoir plus[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;2&#8243; bottom_padding=&#8220;0&#8243; back_color=&#8220;color-lxmt&#8220; overlay_alpha=&#8220;50&#8243; equal_height=&#8220;yes&#8220; gutter_size=&#8220;0&#8243; column_width_percent=&#8220;100&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;2&#8243; bottom_divider=&#8220;step&#8220;][vc_column column_width_percent=&#8220;100&#8243; gutter_size=&#8220;3&#8243; override_padding=&#8220;yes&#8220; column_padding=&#8220;3&#8243; back_color=&#8220;color-xsdn&#8220; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;0&#8243; mobile_width=&#8220;0&#8243; shadow=&#8220;std&#8220; shadow_darker=&#8220;yes&#8220; radius=&#8220;xs&#8220; width=&#8220;2\/3&#8243;][vc_row_inner row_inner_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; limit_content=&#8220;&#8220; row_height_pixel=&#8220;450&#8243;][vc_column_inner column_width_percent=&#8220;100&#8243; gutter_size=&#8220;3&#8243; style=&#8220;light&#8220; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;5&#8243; mobile_width=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243; text_weight=&#8220;300&#8243; text_height=&#8220;fontheight-357766&#8243; text_space=&#8220;fontspace-781688&#8243; separator=&#8220;yes&#8220; separator_color=&#8220;yes&#8220; subheading=&#8220;Une question ?<br \/>\nNous sommes volontiers \u00e0 votre disposition pour de plus amples renseignements sur 1875 FINANCE&#8220;]Contact[\/vc_custom_heading]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f85600-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"85600\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/posts\/86105#wpcf7-f85600-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"85600\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f85600-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vorname\" value=\"\" type=\"text\" name=\"your-firstname\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nachname\" value=\"\" type=\"text\" name=\"your-lastname\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail-Adresse\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Telefon-Nummer\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Nachricht\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"accept-this-1\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"accept-this-1\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Bitten wir Sie, unsere <a href=\"https:\/\/1875.ch\/de\/avertissement\/\" target=\"_blank\"> Datenschutzbestimmungen zu akzeptieren<\/a>.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-accent btn-block\" type=\"submit\" value=\"SENDEN SIE DIE NACHRICHT\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_width_percent=&#8220;100&#8243; align_horizontal=&#8220;align_right&#8220; gutter_size=&#8220;3&#8243; override_padding=&#8220;yes&#8220; column_padding=&#8220;0&#8243; style=&#8220;dark&#8220; back_color=&#8220;accent&#8220; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;0&#8243; mobile_width=&#8220;0&#8243; width=&#8220;1\/3&#8243;][vc_single_image media=&#8220;83070&#8243; media_width_percent=&#8220;100&#8243; media_ratio=&#8220;one-one&#8220;][vc_row_inner row_inner_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column_inner column_width_percent=&#8220;100&#8243; gutter_size=&#8220;3&#8243; expand_height=&#8220;yes&#8220; style=&#8220;dark&#8220; overlay_alpha=&#8220;50&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; shift_y_down=&#8220;0&#8243; z_index=&#8220;0&#8243; medium_width=&#8220;0&#8243; mobile_width=&#8220;0&#8243; width=&#8220;1\/1&#8243; css=&#8220;.vc_custom_1587333600483{padding-right: 10% !important;padding-left: 10% !important;}&#8220;][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243; text_color=&#8220;color-xsdn&#8220; separator=&#8220;yes&#8220; sub_reduced=&#8220;yes&#8220; subheading=&#8220;T\u00e9l\u00e9chargez l\u2019int\u00e9gralit\u00e9 du communiqu\u00e9 de presse de cette nouvelle au format PDF.&#8220;]Communiqu\u00e9[\/vc_custom_heading][vc_button outline=&#8220;yes&#8220; border_width=&#8220;0&#8243; link=&#8220;url:https%3A%2F%2F1875.ch%2Fwp-content%2Fuploads%2F2020%2F05%2F06.10.2008.pdf||target:%20_blank|&#8220;]T\u00e9l\u00e9charger[\/vc_button][vc_empty_space empty_h=&#8220;2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les changements que la crise va causer sur le monde de la finance.<\/p>\n","protected":false},"author":12,"featured_media":83408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-86105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ce que la crise va changer pour le monde de la finance - 1875 Finance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce que la crise va changer pour le monde de la finance - 1875 Finance\" \/>\n<meta property=\"og:description\" content=\"Les changements que la crise va causer sur le monde de la finance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/\" \/>\n<meta property=\"og:site_name\" content=\"1875 Finance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/1875finance\/?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2008-10-06T23:50:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T23:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pixana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"pixana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/\"},\"author\":{\"name\":\"pixana\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#\\\/schema\\\/person\\\/03b814b7966276efa7867843d1c70416\"},\"headline\":\"Ce que la crise va changer pour le monde de la finance\",\"datePublished\":\"2008-10-06T23:50:53+00:00\",\"dateModified\":\"2020-05-26T23:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/\"},\"wordCount\":1813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/header_contact_mobile.jpg\",\"articleSection\":[\"Medienmitteilungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/\",\"url\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/\",\"name\":\"Ce que la crise va changer pour le monde de la finance - 1875 Finance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/header_contact_mobile.jpg\",\"datePublished\":\"2008-10-06T23:50:53+00:00\",\"dateModified\":\"2020-05-26T23:57:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/header_contact_mobile.jpg\",\"contentUrl\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/header_contact_mobile.jpg\",\"width\":667,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/1875.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ce que la crise va changer pour le monde de la finance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/1875.ch\\\/de\\\/\",\"name\":\"1875 Finance\",\"description\":\"The Financial Place to Be\",\"publisher\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1875.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#organization\",\"name\":\"1875 Finance\",\"url\":\"https:\\\/\\\/1875.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1875-logo.png\",\"contentUrl\":\"https:\\\/\\\/1875.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1875-logo.png\",\"width\":220,\"height\":220,\"caption\":\"1875 Finance\"},\"image\":{\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/1875finance\\\/?fref=ts\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZA0ykjGQrrEA3GBFkn8cAg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/1875.ch\\\/de\\\/#\\\/schema\\\/person\\\/03b814b7966276efa7867843d1c70416\",\"name\":\"pixana\",\"sameAs\":[\"https:\\\/\\\/www.pixana.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ce que la crise va changer pour le monde de la finance - 1875 Finance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/","og_locale":"de_DE","og_type":"article","og_title":"Ce que la crise va changer pour le monde de la finance - 1875 Finance","og_description":"Les changements que la crise va causer sur le monde de la finance.","og_url":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/","og_site_name":"1875 Finance","article_publisher":"https:\/\/www.facebook.com\/1875finance\/?fref=ts","article_published_time":"2008-10-06T23:50:53+00:00","article_modified_time":"2020-05-26T23:57:08+00:00","og_image":[{"width":667,"height":750,"url":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg","type":"image\/jpeg"}],"author":"pixana","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"pixana","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#article","isPartOf":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/"},"author":{"name":"pixana","@id":"https:\/\/1875.ch\/de\/#\/schema\/person\/03b814b7966276efa7867843d1c70416"},"headline":"Ce que la crise va changer pour le monde de la finance","datePublished":"2008-10-06T23:50:53+00:00","dateModified":"2020-05-26T23:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/"},"wordCount":1813,"commentCount":0,"publisher":{"@id":"https:\/\/1875.ch\/de\/#organization"},"image":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#primaryimage"},"thumbnailUrl":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg","articleSection":["Medienmitteilungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/","url":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/","name":"Ce que la crise va changer pour le monde de la finance - 1875 Finance","isPartOf":{"@id":"https:\/\/1875.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#primaryimage"},"image":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#primaryimage"},"thumbnailUrl":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg","datePublished":"2008-10-06T23:50:53+00:00","dateModified":"2020-05-26T23:57:08+00:00","breadcrumb":{"@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#primaryimage","url":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg","contentUrl":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/header_contact_mobile.jpg","width":667,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/1875.ch\/de\/ce-que-la-crise-va-changer-pour-le-monde-de-la-finance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/1875.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Ce que la crise va changer pour le monde de la finance"}]},{"@type":"WebSite","@id":"https:\/\/1875.ch\/de\/#website","url":"https:\/\/1875.ch\/de\/","name":"1875 Finance","description":"The Financial Place to Be","publisher":{"@id":"https:\/\/1875.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1875.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/1875.ch\/de\/#organization","name":"1875 Finance","url":"https:\/\/1875.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/1875.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/1875-logo.png","contentUrl":"https:\/\/1875.ch\/wp-content\/uploads\/2020\/03\/1875-logo.png","width":220,"height":220,"caption":"1875 Finance"},"image":{"@id":"https:\/\/1875.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/1875finance\/?fref=ts","https:\/\/www.youtube.com\/channel\/UCZA0ykjGQrrEA3GBFkn8cAg"]},{"@type":"Person","@id":"https:\/\/1875.ch\/de\/#\/schema\/person\/03b814b7966276efa7867843d1c70416","name":"pixana","sameAs":["https:\/\/www.pixana.ch"]}]}},"_links":{"self":[{"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/posts\/86105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/comments?post=86105"}],"version-history":[{"count":0,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/posts\/86105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/media\/83408"}],"wp:attachment":[{"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/media?parent=86105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/categories?post=86105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/1875.ch\/de\/wp-json\/wp\/v2\/tags?post=86105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}